{"id":103458,"date":"2025-12-06T08:01:56","date_gmt":"2025-12-06T06:01:56","guid":{"rendered":"https:\/\/malta-media.com\/?p=103458"},"modified":"2025-12-06T08:08:45","modified_gmt":"2025-12-06T06:08:45","slug":"malita-investments-sucht-geldmittel-bei-stockenden-wohnprojekten","status":"publish","type":"post","link":"https:\/\/malta-media.com\/de\/malita-investments-sucht-geldmittel-bei-stockenden-wohnprojekten\/","title":{"rendered":"Malita Investments sucht Mittel bei stoppenden Wohn Projekte"},"content":{"rendered":"<p><strong>Maltas staatlich unterst\u00fctztes Immobilieninvestmentvehikel Malita Investments plc steht vor einem beispiellosen finanziellen und governancebezogenen R\u00fcckschlag. Das b\u00f6rsennotierte Unternehmen, das traditionell mit der Unterst\u00fctzung gro\u00dfer nationaler Entwicklungsprojekte \u2013 darunter gro\u00df angelegte Sozialwohnungsinitiativen \u2013 betraut ist, sucht nun nach Aussch\u00f6pfung seiner internen Kapitalreserven nach externen Bankfinanzierungen. Die Situation hat Bedenken hinsichtlich der Aufsicht, der strategischen Entscheidungsfindung und der Kontinuit\u00e4t der Governance innerhalb einer Organisation aufgeworfen, die als zentral f\u00fcr das Rahmenwerk des Landes f\u00fcr bezahlbaren Wohnraum gilt.<\/strong><\/p>\n<p>Die j\u00fcngste Ank\u00fcndigung des Unternehmens, die sp\u00e4t am Abend ver\u00f6ffentlicht wurde, offenbar in dem strategischen Bestreben, unmittelbare Marktst\u00f6rungen abzumildern, best\u00e4tigte, dass es drei umfangreiche Sozialwohnungsbauprojekte nicht mehr selbst finanzieren kann. Diese Projekte in Kirkop, Cospicua und Luqa wurden eingestellt, weil es laut Malita keine \u201einterne L\u00f6sung\u201d gibt, mit der die erhebliche Finanzierungsl\u00fccke geschlossen werden k\u00f6nnte. Nach Angaben des Unternehmens bleibt die Aufnahme zus\u00e4tzlicher Kredite nun die \u201eeinzige verbleibende Option\u201d, um den Bau wieder aufzunehmen.<\/p>\n<h2>Liquidit\u00e4tsengp\u00e4sse und dringende Gespr\u00e4che mit Kreditgebern<\/h2>\n<p>Die von Malita beschriebene finanzielle Situation stellt eine deutliche Abweichung von den bisherigen Erwartungen an das Unternehmen dar. In der Vergangenheit galt Malita Investments als relativ finanziell stabil, gest\u00fctzt durch seine mehrheitliche staatliche Beteiligung und seine Position als Vehikel zur B\u00fcndelung \u00f6ffentlicher und privater Investitionen f\u00fcr langfristige Infrastruktur- und Sozialentwicklungsprojekte. Die Notierung an der Malta Stock Exchange sorgte f\u00fcr zus\u00e4tzliche Transparenz, Governance-Regeln und Vertrauen bei den Anlegern.<\/p>\n<p>Personen, die mit den internen Diskussionen vertraut sind, berichten jedoch, dass die Regierung die Bank of Valletta dazu ermutigt, die Bereitstellung des erforderlichen Kredits in Betracht zu ziehen. Ob die Bank letztendlich zustimmen wird, bleibt ungewiss. Die Anfrage steht im Zusammenhang mit den bestehenden finanziellen Verpflichtungen von Malita, zu denen bereits ein betr\u00e4chtlicher Kredit geh\u00f6rt, der zuvor von der Europ\u00e4ischen Investitionsbank gew\u00e4hrt wurde. Die Kreditgeber k\u00f6nnten daher die Risiken einer weiteren Kreditvergabe an ein Unternehmen abw\u00e4gen, das derzeit mit Liquidit\u00e4tsengp\u00e4ssen zu k\u00e4mpfen hat, insbesondere in einem Umfeld, in dem Bauverz\u00f6gerungen, erh\u00f6hte Projektkosten und Fragen der Unternehmensf\u00fchrung das wahrgenommene Risiko erh\u00f6hen k\u00f6nnten.<\/p>\n<p>Malita hat keine der potenziellen Finanzierungsinstitutionen, mit denen es in Verhandlungen steht, \u00f6ffentlich genannt. Dennoch hat das Unternehmen betont, dass die Kreditaufnahme nach wie vor unerl\u00e4sslich ist, um die Dynamik bei Wohnbauprojekten aufrechtzuerhalten, die f\u00fcr die nationale Politik und die Ziele des \u00f6ffentlichen Wohls von strategischer Bedeutung sind.<\/p>\n<h2>Interne F\u00fchrungsprobleme verst\u00e4rken den finanziellen Druck<\/h2>\n<p>Die finanziellen Probleme gehen einher mit erheblichen internen Turbulenzen auf Vorstands- und F\u00fchrungsebene. In den letzten Wochen kam es zu mehreren R\u00fccktritten, was den Eindruck einer Instabilit\u00e4t innerhalb der F\u00fchrungsstruktur erweckt.<\/p>\n<p>Der Unternehmenssekret\u00e4r Albert Cilia reichte kurz nach dem unerwarteten R\u00fccktritt des Unternehmensvorsitzenden Johan Farrugia seine K\u00fcndigung ein. Farrugias R\u00fccktritt wurde nicht \u00f6ffentlich begr\u00fcndet, und Wohnungsbauminister Roderick Galdes lehnte es ab, das R\u00fccktrittsschreiben zu ver\u00f6ffentlichen. Angesichts der strategischen Bedeutung des Auftrags von Malita hat dies in der \u00d6ffentlichkeit und in politischen Kreisen Fragen nach den Gr\u00fcnden f\u00fcr die pl\u00f6tzlichen F\u00fchrungswechsel aufgeworfen.<\/p>\n<p>Die R\u00fccktritte erfolgten auch kurz nach \u00c4u\u00dferungen der ehemaligen Malita-Vorsitzenden und Labour-Europaabgeordneten Marlene Mizzi. Mizzi \u00e4u\u00dferte \u00f6ffentlich Bedenken hinsichtlich der Aufsicht und behauptete, der Minister sei in einem Ma\u00dfe involviert, das ihrer Meinung nach nicht mit der Notwendigkeit einer unabh\u00e4ngigen Unternehmensf\u00fchrung vereinbar sei. Dar\u00fcber hinaus warf sie Fragen hinsichtlich der Beziehungen zu Auftragnehmern auf, die an millionenschweren Projekten beteiligt sind. Angesichts des \u00f6ffentlichen Interesses an solch umfangreichen Investitionen erregten ihre \u00c4u\u00dferungen gro\u00dfe Aufmerksamkeit, obwohl weder Malita noch das Ministerium offiziell ein Fehlverhalten geltend gemacht hatten.<\/p>\n<p>Als Reaktion auf diese Entwicklungen hat Malita davon abgesehen, seine finanziellen Defizite auf Faktoren im Zusammenhang mit der Unternehmensf\u00fchrung zur\u00fcckzuf\u00fchren. Ebenso hat Minister Galdes keine Verantwortung f\u00fcr die finanzielle Lage des Unternehmens \u00fcbernommen. Dies hat einige Beobachter dazu veranlasst, mehr Klarheit in Bezug auf die strategische Aufsicht zu fordern, insbesondere nachdem das <a href=\"https:\/\/malta-media.com\/ALEA\" title=\"ALEA\" class=\"pretty-link-keyword\"rel=\"\" target=\"_blank\">Portfolio<\/a> und die administrative Aufsicht des Unternehmens Mitte 2024 vom Finanzministerium auf das Wohnungsbauministerium \u00fcbertragen wurden.<\/p>\n<h2>Verlagerung der ministeriellen Aufsicht und aufkommende Spannungen<\/h2>\n<p>Malita Investments unterstand zuvor dem Zust\u00e4ndigkeitsbereich von Finanzminister Clyde Caruana. Mit den internen Abl\u00e4ufen vertraute Personen vermuten, dass die Verlagerung der Verwaltung zum Wohnungsbauministerium zu Komplikationen gef\u00fchrt haben k\u00f6nnte. Berichten aus internen Quellen zufolge begannen Beamte des Wohnungsbauministeriums und der Wohnungsbaubeh\u00f6rde nach der Verlagerung, sich st\u00e4rker in Prozesse im Zusammenhang mit der Vergabe von Auftr\u00e4gen und der operativen Aufsicht einzubringen.<\/p>\n<p>Zwar sind die Ministerien berechtigt, \u00f6ffentliche Investitionen zu \u00fcberwachen, doch kann jede wahrgenommene Verlagerung von der Aufsicht hin zur operativen Beteiligung im Zusammenhang mit der Unternehmensf\u00fchrung Bedenken hervorrufen, insbesondere wenn es sich um ein b\u00f6rsennotiertes Unternehmen handelt. In solchen F\u00e4llen sind Unabh\u00e4ngigkeit, transparente Verfahren und die Einhaltung von Beschaffungsstandards nach wie vor von entscheidender Bedeutung, um die Entscheidungsfindung des Unternehmens zu sch\u00fctzen und das Vertrauen der Aktion\u00e4re, Kreditgeber und des Marktes insgesamt zu gew\u00e4hrleisten.<\/p>\n<p>Malita hat eine solche Beteiligung von Ministerialbeamten weder best\u00e4tigt noch eine Erkl\u00e4rung abgegeben, in der klargestellt wird, inwieweit ministerielle Eingriffe die internen Prozesse des Unternehmens beeinflussen. Die Zur\u00fcckhaltung des Unternehmens, die Ursachen f\u00fcr die Finanzierungsl\u00fccke \u00f6ffentlich zu erl\u00e4utern, hat jedoch die Forderungen nach mehr Transparenz verst\u00e4rkt.<\/p>\n<h2>Auswirkungen auf den sozialen Wohnungsbau und das Vertrauen der \u00d6ffentlichkeit<\/h2>\n<p>Die unmittelbare Folge der Liquidit\u00e4tsknappheit ist die Aussetzung der Arbeiten an drei bedeutenden Bauvorhaben, mit denen Maltas Verpflichtungen im Bereich des sozialen Wohnungsbaus unterst\u00fctzt werden sollen. Diese Projekte in Kirkop, Cospicua und Luqa wurden als wichtige Bestandteile der nationalen Strategie zur Verk\u00fcrzung der Wartelisten f\u00fcr Sozialwohnungen und zur Bereitstellung moderner, erschwinglicher Unterk\u00fcnfte f\u00fcr bed\u00fcrftige Familien vorgestellt.<\/p>\n<p>Die Unterbrechung der Bauarbeiten hat bei den Beteiligten, darunter potenzielle Mieter, lokale Beh\u00f6rden und Organisationen, die sich mit Fragen des Zugangs zu Wohnraum befassen, Besorgnis ausgel\u00f6st. Projekte dieser Art sind in der Regel millionenschwere Unternehmungen, die mit hohen Investitionsausgaben verbunden sind. Jede Unterbrechung wirkt sich nicht nur auf den geplanten Zeitplan aus, sondern kann auch zu erh\u00f6hten zuk\u00fcnftigen Kosten f\u00fcr Materialien, Arbeitskr\u00e4fte, Vertragsanpassungen und m\u00f6glichen Strafen f\u00fchren.<\/p>\n<p>L\u00e4ngere Verz\u00f6gerungen k\u00f6nnen je nach Ausma\u00df der Unterbrechung auch eine Neugestaltung des Projekts oder aktualisierte beh\u00f6rdliche Genehmigungen erforderlich machen. Marktbeobachter stellen fest, dass selbst vor\u00fcbergehende Unterbrechungen dauerhafte Auswirkungen auf die Lieferf\u00e4higkeit und die finanzielle Nachhaltigkeit haben k\u00f6nnen.<\/p>\n<h2>Unklarheit \u00fcber die Finanzierungsl\u00fccke<\/h2>\n<p>In seiner Ank\u00fcndigung hat Malita keine genauen Angaben zur H\u00f6he der Finanzierungsl\u00fccke gemacht. Diese Auslassung hat zu Spekulationen \u00fcber das Ausma\u00df des Defizits und die allgemeine finanzielle Lage des Unternehmens gef\u00fchrt. Ohne Klarheit m\u00fcssen die Stakeholder die Solvenz und Liquidit\u00e4t des Unternehmens m\u00f6glicherweise anhand \u00f6ffentlich zug\u00e4nglicher Finanzberichte beurteilen, die m\u00f6glicherweise nicht die aktuellen betrieblichen Gegebenheiten widerspiegeln.<\/p>\n<p>Es ist auch unklar, ob die Finanzierungsl\u00fccke auf steigende Baukosten, eskalierende Materialpreise, Vertrags\u00e4nderungen oder andere Faktoren zur\u00fcckzuf\u00fchren ist. In Malta haben die Inflation im Bausektor und St\u00f6rungen in der Lieferkette in den letzten Jahren zu einem erheblichen Anstieg der Projektkosten gef\u00fchrt. Wenn die Kostenprognosen von Malita auf fr\u00fcheren Preisannahmen basierten, k\u00f6nnte sich der Druck auf die Finanzen des Unternehmens rapide versch\u00e4rft haben.<\/p>\n<p>Unabh\u00e4ngig von der Ursache hat das Unternehmen ausdr\u00fccklich erkl\u00e4rt, dass die internen Kapitaloptionen nun ausgesch\u00f6pft sind, was eine strukturelle Herausforderung verdeutlicht, die nicht nur eine externe Finanzierung, sondern auch eine langfristige Neubewertung der Budgetierungs- und Projektmanagementstrategien erfordert.<\/p>\n<h2>Reaktion der Regierung und politische Sensibilit\u00e4ten<\/h2>\n<p>Premierminister Robert Abela hat sich trotz Fragen verschiedener Interessengruppen zur Stabilit\u00e4t der F\u00fchrung von Malita und zur Zukunft wichtiger Sozialwohnungsprojekte nicht \u00f6ffentlich ge\u00e4u\u00dfert. Beobachter weisen darauf hin, dass die Rolle der Regierung als Mehrheitsaktion\u00e4r zwar eine Aufsichtsfunktion mit sich bringt, aber auch die Verpflichtung, eine \u00fcberm\u00e4\u00dfige Einflussnahme auf operative Entscheidungen des Vorstands und des Managementteams zu vermeiden.<\/p>\n<p>Bis heute hat der Wohnungsbauminister weder die politische Verantwortung f\u00fcr die finanzielle Lage des Unternehmens \u00fcbernommen noch detaillierte Informationen \u00fcber die Umst\u00e4nde vorgelegt, die zur aktuellen Situation gef\u00fchrt haben. Das Ministerium hat sich auch nicht zu Fragen von \u00f6ffentlichem Interesse ge\u00e4u\u00dfert, die sich aus den j\u00fcngsten R\u00fccktritten der F\u00fchrungsspitze ergeben haben.<\/p>\n<p>Politische Kommentatoren weisen darauf hin, dass die Wohnungspolitik nach wie vor ein wichtiges Thema auf der nationalen <a href=\"https:\/\/malta-media.com\/sigma\" title=\"SiGMA\" class=\"pretty-link-keyword\"rel=\"\" target=\"_blank\">Agenda<\/a> ist. Daher kann jede St\u00f6rung der Bereitstellung von Sozialwohnungen politische Auswirkungen haben. Dennoch scheint die Regierung einen vorsichtigen Ansatz zu verfolgen, wahrscheinlich um das Risiko einer Destabilisierung der laufenden Finanzverhandlungen oder einer zus\u00e4tzlichen Verunsicherung der Investoren zu minimieren.<\/p>\n<h2>Fragen zu den Verm\u00f6genserkl\u00e4rungen des Ministers<\/h2>\n<p>Zum breiteren politischen Kontext geh\u00f6ren auch Kommentare zu den pers\u00f6nlichen Verm\u00f6genswerten des Ministers. Es wurde berichtet, dass der Minister f\u00fcr bezahlbaren Wohnraum seit seinem Amtsantritt sein Immobilienportfolio erweitert hat, w\u00e4hrend er ein bescheidenes Einkommen angibt. Diese Angelegenheiten wurden in der \u00f6ffentlichen Debatte angesprochen, obwohl keine formellen Vorw\u00fcrfe in Bezug auf Malita oder seine Projekte erhoben wurden. Dennoch tragen solche Kommentare zu dem hochsensiblen Umfeld bei, das die aktuellen Herausforderungen der Regierungsf\u00fchrung umgibt.<\/p>\n<p>Angesichts der Tatsache, dass fr\u00fchere Medienberichte Berichten zufolge zu rechtlichen Schrifts\u00e4tzen der beteiligten Personen gef\u00fchrt haben, ist es nach wie vor unerl\u00e4sslich, \u00fcber diese Angelegenheiten unter strikter Einhaltung der sachlichen Genauigkeit und ohne Andeutungen \u00fcber das hinaus, was \u00f6ffentlich bekannt gegeben wurde, zu berichten. Es wurde kein Fehlverhalten festgestellt, und es wurden keine offiziellen Untersuchungen angek\u00fcndigt.<\/p>\n<h2>Der Weg in die Zukunft f\u00fcr Malita Investments<\/h2>\n<p>Malita befindet sich derzeit an einem kritischen Punkt. Die Sicherung neuer Finanzmittel wird nicht nur f\u00fcr die Fertigstellung der gestoppten Projekte unerl\u00e4sslich sein, sondern auch f\u00fcr die Aufrechterhaltung des Marktvertrauens und die Erf\u00fcllung der Verpflichtungen gegen\u00fcber den Stakeholdern. B\u00f6rsennotierte Unternehmen, die auf das Vertrauen der Anleger angewiesen sind, m\u00fcssen sicherstellen, dass ihre Governance-Strukturen robust und transparent sind und vor unzul\u00e4ssigen externen Einfl\u00fcssen gesch\u00fctzt sind.<\/p>\n<p>Die n\u00e4chsten Schritte des Unternehmens werden wahrscheinlich detaillierte Verhandlungen mit potenziellen Kreditgebern, interne Governance-\u00dcberpr\u00fcfungen und eine erneute Kommunikation mit den Aktion\u00e4ren umfassen. Diese Ma\u00dfnahmen k\u00f6nnten dazu beitragen, die Ausrichtung des Unternehmens zu stabilisieren und seine langfristige Rolle in der sozialen und infrastrukturellen Entwicklung Maltas zu st\u00e4rken.<\/p>\n<h2>Fazit<\/h2>\n<p><strong>Die sich derzeit entwickelnde Situation bei Malita Investments ist mehr als nur eine vor\u00fcbergehende Finanzierungsunterbrechung; sie spiegelt einen entscheidenden Moment f\u00fcr eines der strategisch wichtigsten \u00f6ffentlichen Investitionsvehikel Maltas wider. W\u00e4hrend das Unternehmen daran arbeitet, neue Finanzmittel zu sichern und die Kontinuit\u00e4t seiner eingestellten Sozialwohnungsprojekte wiederherzustellen, muss es sich auch der ebenso dringenden Aufgabe stellen, die internen Governance-Strukturen zu st\u00e4rken und das Vertrauen des Marktes wiederherzustellen. Die Kombination aus finanzieller Belastung, F\u00fchrungswechseln und verst\u00e4rkter \u00f6ffentlicher Kontrolle unterstreicht die Bedeutung transparenter Verfahren, disziplinierter Aufsicht und klarer Kommunikation \u2013 insbesondere f\u00fcr Unternehmen, die mit der Verwaltung von Projekten betraut sind, die sich direkt auf das \u00f6ffentliche Wohl auswirken.<\/strong><\/p>\n<p><strong>Zwar wurden keine Verfehlungen behauptet, doch die Sensibilit\u00e4t im Zusammenhang mit den j\u00fcngsten R\u00fccktritten, politischen Kommentaren und administrativen Kontrollen unterstreicht die Notwendigkeit eines stabilen und klar definierten operativen Rahmens. F\u00fcr Malita wird der Weg in die Zukunft davon abh\u00e4ngen, ob es dem Unternehmen gelingt, Widerstandsf\u00e4higkeit zu beweisen, verst\u00e4rkte Governance-Praktiken umzusetzen und die Unabh\u00e4ngigkeit seiner Entscheidungsprozesse zu wahren. F\u00fcr die breite \u00d6ffentlichkeit besteht die Hoffnung, dass diese Herausforderungen die notwendigen Reformen vorantreiben werden, um langfristig Stabilit\u00e4t bei der Bereitstellung der wesentlichen Wohnungsinfrastruktur zu gew\u00e4hrleisten.<\/strong><\/p>\n<p><strong>Letztendlich wird die Entwicklung von Malita in den kommenden Monaten nicht nur die Zukunft der ausgesetzten Bauvorhaben pr\u00e4gen, sondern auch das Vertrauen der \u00d6ffentlichkeit in die Systeme, die f\u00fcr die Umsetzung der nationalen Wohnraumpriorit\u00e4ten verantwortlich sind. Die n\u00e4chsten Schritte des Unternehmens \u2013 insbesondere in den Bereichen Finanzierung, Unternehmensf\u00fchrung und Kommunikation mit den Interessengruppen \u2013 werden daher f\u00fcr die gesamte soziale und infrastrukturelle Landschaft Maltas von erheblicher Bedeutung sein.<\/strong><\/p>\n<h2>H\u00e4ufig gestellte Fragen<\/h2>\n<p><strong>Was ist Malita Investments plc?<\/strong><br \/>\nMalita Investments plc ist ein b\u00f6rsennotiertes Unternehmen in Malta, das staatlich gef\u00f6rderte Entwicklungsprojekte, darunter bedeutende Sozialwohnungsinitiativen, verwaltet.<\/p>\n<p><strong>Warum hat Malita seine Bauprojekte eingestellt?<\/strong><br \/>\nMalita hat den Bau aufgrund einer Finanzierungsl\u00fccke unterbrochen und erkl\u00e4rt, dass es \u201ekeine interne L\u00f6sung\u201d gebe, um die Arbeiten an drei gro\u00dfen Sozialwohnungsprojekten fortzusetzen.<\/p>\n<p><strong>Welche Projekte sind davon betroffen?<\/strong><br \/>\nDie gestoppten Projekte befinden sich in Kirkop, Cospicua und Luqa und sind alle Teil der umfassenden Strategie Maltas f\u00fcr den sozialen Wohnungsbau.<\/p>\n<p><strong>Warum sucht Malita nach einer Bankfinanzierung?<\/strong><br \/>\nDas Unternehmen gab an, dass externe Kredite die \u201eeinzige verbleibende Option\u201d seien, um die Finanzierungsl\u00fccke zu schlie\u00dfen und die Projektarbeiten wieder aufzunehmen.<\/p>\n<p><strong>Hat Malita die H\u00f6he der Finanzierungsl\u00fccke offengelegt?<\/strong><br \/>\nNein, Malita hat die genaue H\u00f6he der Finanzierungsl\u00fccke nicht \u00f6ffentlich bekannt gegeben.<\/p>\n<p><strong>Warum gab es k\u00fcrzlich R\u00fccktritte im Unternehmen?<\/strong><br \/>\nDer Unternehmenssekret\u00e4r und der Vorsitzende sind k\u00fcrzlich zur\u00fcckgetreten, allerdings wurde keine offizielle Erkl\u00e4rung f\u00fcr den R\u00fccktritt des Vorsitzenden abgegeben.<\/p>\n<p><strong>Ist die Regierung an den Entscheidungen von Malita beteiligt?<\/strong><br \/>\nBerichten zufolge ist seit Mitte 2024 eine verst\u00e4rkte Beteiligung des Ministeriums zu beobachten, allerdings hat Malita den Umfang dieser Beteiligung nicht best\u00e4tigt.<\/p>\n<p><strong>Wird die Bank of Valletta Malita Finanzmittel zur Verf\u00fcgung stellen?<\/strong><br \/>\nEs ist unklar, ob die Bank of Valletta einer Verl\u00e4ngerung der Finanzierung zustimmen wird, da die Gespr\u00e4che Berichten zufolge noch andauern.<\/p>\n<p><strong>Wurden irgendwelche Verfehlungen behauptet?<\/strong><br \/>\nWeder Malita noch das Ministerium oder eine Aufsichtsbeh\u00f6rde haben offiziell Verfehlungen behauptet.<\/p>\n<p><strong>Wie geht es nun mit den Sozialwohnungsprojekten weiter?<\/strong><br \/>\nDie Projekte werden wahrscheinlich wieder aufgenommen, sobald die Finanzierung gesichert ist, auch wenn der Zeitplan noch ungewiss ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malita sucht Kreditgeber, da Finanzierungsl\u00fccken und Governance Spannungen zentrale Sozial Wohnungs Projekte belasten.<\/p>\n","protected":false},"author":14,"featured_media":103456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[579],"tags":[81181,59827,81183,10635,1467,81180,78734,587,81179,788,81182,60498,81184],"class_list":["post-103458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-malta-news","tag-bausektor-malta","tag-corporate-governance-malta-de","tag-entwicklungsprojekte-malta","tag-financial-stability-de","tag-finanzielle-stabilitaet","tag-governance-aufsicht","tag-malita-investments-de","tag-malta-news","tag-maltesische-wohnpolitik","tag-news-malta-de","tag-oeffentliche-investitionen-malta","tag-sozialwohnungen-malta","tag-wohnungsministerium-malta"],"acf":[],"_links":{"self":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/103458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/comments?post=103458"}],"version-history":[{"count":0,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/103458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media\/103456"}],"wp:attachment":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media?parent=103458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/categories?post=103458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/tags?post=103458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}