{"id":109125,"date":"2026-01-30T12:06:46","date_gmt":"2026-01-30T10:06:46","guid":{"rendered":"https:\/\/malta-media.com\/?p=109125"},"modified":"2026-01-30T12:06:46","modified_gmt":"2026-01-30T10:06:46","slug":"minister-lehnt-veroffentlichung-des-detaillierten-mcast-berichts-ab","status":"publish","type":"post","link":"https:\/\/malta-media.com\/de\/minister-lehnt-veroffentlichung-des-detaillierten-mcast-berichts-ab\/","title":{"rendered":"Minister lehnt Ver\u00f6ffentlichung des detaillierten MCAST Berichts ab"},"content":{"rendered":"<p><strong>Die Entscheidung des Bildungsministeriums, die vollst\u00e4ndigen Ergebnisse einer Verwaltungsuntersuchung zu den Finanzkontrollen am Malta College of Arts Science and <a href=\"https:\/\/malta-media.com\/ALEA\" title=\"ALEA\" class=\"pretty-link-keyword\"rel=\"\" target=\"_blank\">Technology<\/a> nicht zu ver\u00f6ffentlichen, hat erneut langj\u00e4hrige Bedenken hinsichtlich der Transparenz, Rechenschaftspflicht und Governance innerhalb \u00f6ffentlicher Einrichtungen aufkommen lassen. Trotz wiederholter Anfragen von Journalisten und klarer Aussagen des Untersuchungsausschusses selbst, dass die detaillierten Ergebnisse ein integraler Bestandteil des Berichts sind, hat das Ministerium die Ver\u00f6ffentlichung auf eine kurze Pressemitteilung beschr\u00e4nkt.<\/strong><\/p>\n<p>Im Mittelpunkt der Kontroverse steht eine Untersuchung, die nach einer Unterschlagungsermittlung am MCAST eingeleitet wurde und zu einer Strafanzeige gegen die ehemalige Finanzkontrolleurin der Einrichtung, Francine Farrugia, f\u00fchrte. W\u00e4hrend das Strafverfahren noch l\u00e4uft, hat die Handhabung der Verwaltungsuntersuchung zu einer erneuten \u00dcberpr\u00fcfung gef\u00fchrt, wie mit Vers\u00e4umnissen bei der Aufsicht umgegangen wird und wie viele Informationen die \u00d6ffentlichkeit erhalten darf, wenn in \u00f6ffentlich finanzierten Einrichtungen schwerwiegende Governance-Probleme auftreten.<\/p>\n<p>Diese Situation hat auch Fragen zur ministeriellen Verantwortung und zur Unabh\u00e4ngigkeit von Untersuchungsprozessen aufgeworfen, insbesondere angesichts des Hintergrunds und der vielf\u00e4ltigen \u00f6ffentlichen \u00c4mter, die der ernannte Untersuchungsvorsitzende innehat.<\/p>\n<h2>Begrenzte Offenlegung trotz \u00f6ffentlichen Interesses<\/h2>\n<p>Bildungsminister Clifton Grima hat es bisher abgelehnt, substanziell auf Fragen von The Shift bez\u00fcglich der Entscheidung, den vollst\u00e4ndigen Bericht \u00fcber die Verwaltungsuntersuchung nicht zu ver\u00f6ffentlichen, zu antworten. Die Reaktion des Ministeriums beschr\u00e4nkte sich auf die Ver\u00f6ffentlichung einer Pressemitteilung, in der die Existenz der Untersuchung zusammengefasst und die zuk\u00fcnftige Umsetzung ihrer Empfehlungen zugesichert wird.<\/p>\n<p>In dieser Mitteilung fehlen insbesondere die spezifischen M\u00e4ngel, die w\u00e4hrend der Untersuchung der Finanzkontrollen von MCAST festgestellt wurden. Diese Auslassung ist bemerkenswert, da die Untersuchung auf jahrelange Warnungen des Nationalen Rechnungshofs hinsichtlich interner Schw\u00e4chen der Einrichtung folgte. Diese Warnungen gingen dem Strafverfahren voraus, das nun gegen den ehemaligen Finanzkontrolleur von MCAST gef\u00fchrt wird.<\/p>\n<p>Das Fehlen von Details hat Beobachter dazu veranlasst, sich zu fragen, wie eine sinnvolle Rechenschaftspflicht erreicht werden kann, wenn der \u00d6ffentlichkeit der Zugang zu genau den Informationen verwehrt wird, die erkl\u00e4ren, was schiefgelaufen ist und warum.<\/p>\n<h2>Hintergrund der Verwaltungsuntersuchung<\/h2>\n<p>Die Verwaltungsuntersuchung wurde im August des Vorjahres vor dem Hintergrund schwerwiegender Vorw\u00fcrfe bez\u00fcglich der Finanzverwaltung bei MCAST angek\u00fcndigt. Diese Vorw\u00fcrfe gipfelten in einer Strafanzeige gegen Francine Farrugia, eine ehemalige PN-Gemeinder\u00e4tin, die als Finanzkontrolleurin der Einrichtung t\u00e4tig war.<\/p>\n<p>W\u00e4hrend sich das Strafverfahren auf die individuelle Verantwortung konzentriert, sollte die Verwaltungsuntersuchung umfassendere systemische Fragen untersuchen, darunter F\u00fchrungsstrukturen, interne Kontrollen und die Aufsicht durch die Leitung. Solche Untersuchungen dienen in der Regel dazu, institutionelle Vers\u00e4umnisse aufzudecken und Korrekturma\u00dfnahmen vorzuschlagen, um eine Wiederholung zu verhindern.<\/p>\n<p>Von Anfang an stie\u00df die Untersuchung jedoch auf Skepsis, insbesondere hinsichtlich ihrer Unabh\u00e4ngigkeit und der Frage, inwieweit ihre Ergebnisse ver\u00f6ffentlicht werden w\u00fcrden.<\/p>\n<h2>Erkl\u00e4rung und Zusicherungen des Ministeriums<\/h2>\n<p>In seiner offiziellen Erkl\u00e4rung versuchte das Bildungsministerium, die \u00d6ffentlichkeit zu beruhigen, dass Ma\u00dfnahmen ergriffen w\u00fcrden. In der Erkl\u00e4rung hei\u00dft es<\/p>\n<p>\u201eDas Ministerium versichert, dass dieser Bericht bei MCAST in Bezug auf parallele Verfahren, die derzeit vor Gericht anh\u00e4ngig sind, umgesetzt wird. Um jegliche Zweideutigkeiten zu vermeiden, wird das Begleitschreiben zu dieser Untersuchung dieser Pressemitteilung beigef\u00fcgt.\u201c<\/p>\n<p>Diese Formulierung deutet zwar auf eine Reformbereitschaft hin, bietet jedoch wenig Klarheit dar\u00fcber, welche konkreten Ma\u00dfnahmen vorgesehen sind und wie sie die im Rahmen der Untersuchung festgestellten Schwachstellen beheben sollen. Der Verweis auf parallele Gerichtsverfahren wurde von einigen auch als Rechtfertigung f\u00fcr die Zur\u00fcckhaltung detaillierter Informationen und nicht als rechtliche Notwendigkeit interpretiert.<\/p>\n<h2>Die Bedeutung des Begleitschreibens<\/h2>\n<p>Das einzige substanzielle Dokument, das zusammen mit der Erkl\u00e4rung des Ministeriums ver\u00f6ffentlicht wurde, war das Begleitschreiben, das vom Untersuchungsausschuss selbst verfasst wurde. Dieses Schreiben liefert wichtige Hintergrundinformationen, die verdeutlichen, warum das Fehlen des vollst\u00e4ndigen Berichts problematisch ist.<\/p>\n<p>Nach Angaben des Ausschusses fanden w\u00e4hrend der Untersuchung neun separate Anh\u00f6rungen statt. Mehrere Zeugen sagten aus, und es wurde ein detaillierter technischer Bericht erstellt. Der Ausschuss bezeichnete sowohl die Zeugenaussagen als auch den technischen Bericht ausdr\u00fccklich als \u201ewesentliche Bestandteile\u201d der Schlussfolgerungen der Untersuchung.<\/p>\n<h2>In dem Schreiben hei\u00dft es weiter<\/h2>\n<p>\u201eNach sorgf\u00e4ltiger Lekt\u00fcre dieser Zeugenaussagen und der (in diesem technischen Bericht) vorgelegten Dokumente kann man zu dem Schluss kommen, dass der Zustand der F\u00fchrung der MCAST nicht optional ist.\u201d<\/p>\n<p>Der Ausschuss betonte auch, dass seine Schlussfolgerungen auf einer bestimmten Seite des technischen Berichts zu finden sind, und merkte an, dass dieser Abschnitt \u201eReflexion und sorgf\u00e4ltiges Lesen erfordert\u201d.<\/p>\n<p>Diese Bemerkungen deuten stark darauf hin, dass die wichtigsten Ergebnisse eher in dem unver\u00f6ffentlichten Material als in der vom Ministerium ver\u00f6ffentlichten kurzen Zusammenfassung enthalten sind.<\/p>\n<h2>Zur\u00fcckhaltung von Informationen und \u00f6ffentliches Vertrauen<\/h2>\n<p>Die Entscheidung, den vollst\u00e4ndigen Bericht nicht zu ver\u00f6ffentlichen, hat Kritik vonseiten derjenigen hervorgerufen, die argumentieren, dass Transparenz f\u00fcr die Aufrechterhaltung des \u00f6ffentlichen Vertrauens unerl\u00e4sslich ist, insbesondere wenn \u00f6ffentliche Gelder und \u00f6ffentliche Einrichtungen beteiligt sind.<\/p>\n<p>Ohne Zugang zu den detaillierten Ergebnissen ist es f\u00fcr die \u00d6ffentlichkeit schwierig zu beurteilen, ob die vorgeschlagenen Reformen angemessen sind oder ob die Verantwortung \u00fcber die Person hinausgeht, gegen die strafrechtliche Vorw\u00fcrfe erhoben werden. Die fehlende Offenlegung schr\u00e4nkt auch eine fundierte Debatte \u00fcber Governance-Standards innerhalb der MCAST und \u00e4hnlicher Einrichtungen ein.<\/p>\n<p>Aus journalistischer Sicht verst\u00e4rkt das Ausbleiben von Antworten auf direkte Fragen zum Inhalt des Berichts die Bedenken hinsichtlich der Rechenschaftspflicht auf Ministerebene.<\/p>\n<h2>Warnungen des National Audit Office und Vers\u00e4umnisse bei der Aufsicht<\/h2>\n<p>Einer der beunruhigendsten Aspekte des Falls ist die offensichtliche Diskrepanz zwischen den jahrelangen Warnungen des National Audit Office und dem sp\u00e4teren Aufkommen strafrechtlicher Vorw\u00fcrfe. In den Berichten des NAO wurden wiederholt Schw\u00e4chen bei der Finanzkontrolle der MCAST hervorgehoben, lange bevor die mutma\u00dfliche Veruntreuung \u00f6ffentlich bekannt wurde.<\/p>\n<p>Diese Warnungen werfen berechtigte Fragen dar\u00fcber auf, ob die Leitung von MCAST und das f\u00fcr die Aufsicht \u00fcber die Einrichtung zust\u00e4ndige Ministerium ausreichende Ma\u00dfnahmen ergriffen haben. Die Verwaltungsuntersuchung sollte Licht in diese Fragen bringen und kl\u00e4ren, wie die Aufsichtsmechanismen versagt haben.<\/p>\n<p>Da der vollst\u00e4ndige Bericht nicht vorliegt, bleiben diese Fragen weitgehend unbeantwortet.<\/p>\n<h2>Skepsis hinsichtlich der Unabh\u00e4ngigkeit der Untersuchung<\/h2>\n<p>Als die Verwaltungsuntersuchung erstmals angek\u00fcndigt wurde, stie\u00df sie nicht nur wegen der versprochenen begrenzten Transparenz, sondern auch wegen des Profils ihres Vorsitzenden auf Skepsis.<\/p>\n<p>Die Untersuchung wurde von dem pensionierten Richter Antonio Mizzi geleitet, der enge pers\u00f6nliche und berufliche Verbindungen zur Regierung hat. Mizzi ist mit der ehemaligen Europaabgeordneten der Labour Party, Marlene Mizzi, verheiratet und hat im Laufe der Jahre mehrere Regierungs\u00e4mter bekleidet.<\/p>\n<p>Unter anderem ist Mizzi Vorsitzender der Beh\u00f6rde f\u00fcr Integrit\u00e4t im maltesischen Sport, eine Position, in die er von Bildungsminister Clifton Grima pers\u00f6nlich berufen wurde. Au\u00dferdem ist er Vorsitzender der Embryo Protection Foundation, der Bew\u00e4hrungskommission f\u00fcr Strafgefangene und Leiter des Amtes des Rechtskommissars.<\/p>\n<p>Zwar ist die Aus\u00fcbung mehrerer \u00f6ffentlicher \u00c4mter an sich nicht unzul\u00e4ssig, doch Kritiker argumentieren, dass eine derart umfangreiche Beteiligung an von der Regierung besetzten Positionen den Eindruck von Befangenheit erwecken kann, insbesondere wenn es um die Leitung von Untersuchungen zu politisch sensiblen Themen geht.<\/p>\n<h2>Ein Muster der Abh\u00e4ngigkeit von bekannten Pers\u00f6nlichkeiten<\/h2>\n<p>Beobachter haben festgestellt, dass die Regierung nach \u00f6ffentlichen Skandalen h\u00e4ufig Antonio Mizzi mit der Leitung von Untersuchungen beauftragt hat. Dies war auch der Fall w\u00e4hrend der Sozialbetrugssaga um den ehemaligen Labour-Abgeordneten Silvio Grixti, bei der Mizzi erneut mit einer als unabh\u00e4ngig bezeichneten Untersuchung betraut wurde.<\/p>\n<p>Diese wiederkehrende Abh\u00e4ngigkeit von derselben Person hat die Debatte dar\u00fcber angeheizt, ob alternative Mechanismen die wahrgenommene und tats\u00e4chliche Unabh\u00e4ngigkeit besser gew\u00e4hrleisten k\u00f6nnten. In Kontexten, in denen das Vertrauen der \u00d6ffentlichkeit bereits angespannt ist, k\u00f6nnen Wahrnehmungen ebenso wichtig sein wie formelle Zusicherungen.<\/p>\n<h2>Verantwortlichkeit der F\u00fchrungsspitze bei MCAST<\/h2>\n<p>Trotz der Schwere der Vorw\u00fcrfe und des anschlie\u00dfenden Strafverfahrens gegen einen hochrangigen Beamten hat die F\u00fchrungsspitze von MCAST bislang erhebliche \u00f6ffentliche Konsequenzen vermieden. Dies hat die Kritik verst\u00e4rkt, dass die Verantwortlichkeit eher auf Einzelpersonen als auf systemische oder managementbezogene Verantwortung ausgerichtet ist.<\/p>\n<p>Die Formulierungen des Untersuchungsausschusses lassen darauf schlie\u00dfen, dass F\u00fchrungsprobleme im Mittelpunkt seiner Ergebnisse standen. Indem der Ausschuss die F\u00fchrungssituation bei MCAST als eine Angelegenheit beschrieb, die \u201enicht optional\u201c sei, deutete er an, dass eine Reform der Unternehmensf\u00fchrung unerl\u00e4sslich und nicht freiwillig ist.<\/p>\n<p>Da die detaillierte Analyse jedoch nicht \u00f6ffentlich zug\u00e4nglich ist, bleibt unklar, wie die Rechenschaftspflicht der F\u00fchrung durchgesetzt oder gemessen werden soll.<\/p>\n<h2>Ausgewogenheit zwischen rechtlicher Vorsicht und Transparenz<\/h2>\n<p>Regierungsbeamte f\u00fchren h\u00e4ufig laufende Gerichtsverfahren als Grund f\u00fcr die Einschr\u00e4nkung der Offenlegung an. Rechtliche Vorsicht ist zwar insbesondere in Strafsachen wichtig, muss jedoch gegen das Recht der \u00d6ffentlichkeit abgewogen werden, zu verstehen, wie \u00f6ffentliche Einrichtungen verwaltet werden.<\/p>\n<p>Verwaltungsuntersuchungen dienen einem anderen Zweck als Strafverfahren. Ihr Schwerpunkt liegt in der Regel auf Systemprozessen und Governance und nicht auf der Feststellung der Schuld. Daher argumentieren viele, dass die Ver\u00f6ffentlichung ihrer Ergebnisse bei sorgf\u00e4ltiger Handhabung nicht unbedingt Rechtsverfahren beeintr\u00e4chtigt.<\/p>\n<p>In diesem Fall hat das Ministerium weder \u00f6ffentlich erkl\u00e4rt, warum eine teilweise Offenlegung als notwendig erachtet wurde, noch hat es angegeben, ob der vollst\u00e4ndige Bericht zu einem sp\u00e4teren Zeitpunkt ver\u00f6ffentlicht werden k\u00f6nnte.<\/p>\n<h2>Auswirkungen auf Governance-Standards<\/h2>\n<p>Die Behandlung der MCAST-Untersuchung hat weitreichende Auswirkungen auf die Governance-Standards im gesamten \u00f6ffentlichen Sektor Maltas. Transparenz nach institutionellem Versagen wird oft als Schl\u00fcsselelement von Reformen genannt. Ohne sie k\u00f6nnten Bem\u00fchungen zum Wiederaufbau von Vertrauen ins Leere laufen.<\/p>\n<p>Der Fall unterstreicht auch, wie wichtig es ist, entschlossen auf Warnungen von Rechnungspr\u00fcfern zu reagieren und sicherzustellen, dass die Aufsichtsbeh\u00f6rden \u00fcber die erforderlichen Befugnisse und die Unabh\u00e4ngigkeit verf\u00fcgen, um Ver\u00e4nderungen herbeizuf\u00fchren.<\/p>\n<h2>Fazit<\/h2>\n<p><strong>Die Weigerung, den vollst\u00e4ndigen Bericht \u00fcber die administrative Untersuchung der Finanzkontrollen von MCAST zu ver\u00f6ffentlichen, hat wichtige Fragen offen gelassen. Das Bildungsministerium hat zwar Zusicherungen hinsichtlich der k\u00fcnftigen Umsetzung gegeben, doch das Fehlen detaillierter Informationen untergr\u00e4bt diese Zusicherungen und sch\u00fcrt Skepsis hinsichtlich der Rechenschaftspflicht.<\/strong><\/p>\n<p><strong>Der Untersuchungsausschuss selbst betonte, dass seine detaillierten Ergebnisse f\u00fcr das Verst\u00e4ndnis der Situation bei MCAST von entscheidender Bedeutung sind. Durch die Zur\u00fcckhaltung dieser Details hat das Ministerium die \u00f6ffentliche Kontrolle eingeschr\u00e4nkt, obwohl Offenheit in diesem Fall wahrscheinlich im \u00f6ffentlichen Interesse w\u00e4re.<\/strong><\/p>\n<p><strong>W\u00e4hrend das Strafverfahren gegen den ehemaligen Finanzkontrolleur weiterl\u00e4uft, bleiben die allgemeineren Fragen der F\u00fchrungsverantwortung und Transparenz in der Unternehmensf\u00fchrung ungel\u00f6st. Die Art und Weise, wie diese Fragen angegangen werden, wird das Vertrauen der \u00d6ffentlichkeit nicht nur in MCAST, sondern auch in die Aufsicht \u00fcber \u00f6ffentliche Einrichtungen im Allgemeinen pr\u00e4gen.<\/strong><\/p>\n<h2>H\u00e4ufig gestellte Fragen<\/h2>\n<p><strong>Warum hat das Bildungsministerium eine Verwaltungsuntersuchung bei MCAST durchgef\u00fchrt?<\/strong><br \/>\nDie Untersuchung wurde eingeleitet, um Fragen der Unternehmensf\u00fchrung und Finanzkontrolle bei MCAST zu pr\u00fcfen, nachdem eine Unterschlagungsuntersuchung zu strafrechtlichen Anklagen gegen einen hochrangigen Beamten gef\u00fchrt hatte.<\/p>\n<p><strong>Warum wurde der vollst\u00e4ndige Untersuchungsbericht nicht ver\u00f6ffentlicht?<\/strong><br \/>\nDas Ministerium hat keine detaillierte Erkl\u00e4rung abgegeben, sondern sich auf laufende Gerichtsverfahren berufen und die Offenlegung auf eine Pressemitteilung und ein Begleitschreiben beschr\u00e4nkt.<\/p>\n<p><strong>Was hat die Untersuchungskommission zu ihren Ergebnissen gesagt?<\/strong><br \/>\nDie Kommission erkl\u00e4rte, dass Zeugenaussagen und ein technischer Bericht wesentliche Bestandteile ihrer Schlussfolgerungen seien, und betonte, wie wichtig es sei, diese Details sorgf\u00e4ltig zu pr\u00fcfen.<\/p>\n<p><strong>Wer leitete die Verwaltungsuntersuchung?<\/strong><br \/>\nDie Untersuchung wurde von dem pensionierten Richter Antonio Mizzi geleitet, der mehrere von der Regierung ernannte \u00c4mter innehat.<\/p>\n<p><strong>Welche Bedenken wurden hinsichtlich der Unabh\u00e4ngigkeit der Untersuchung ge\u00e4u\u00dfert?<\/strong><br \/>\nKritiker verweisen auf die engen Verbindungen des Vorsitzenden zur Regierung und seine zahlreichen \u00f6ffentlichen \u00c4mter als Faktoren, die die Wahrnehmung der Unabh\u00e4ngigkeit beeintr\u00e4chtigen k\u00f6nnten.<\/p>\n<p><strong>In welchem Zusammenhang steht dies mit den Warnungen des National Audit Office?<\/strong><br \/>\nDas NAO hatte bereits Jahre vor Bekanntwerden der strafrechtlichen Vorw\u00fcrfe Warnungen bez\u00fcglich der Finanzkontrollen von MCAST ausgesprochen, was Fragen zur Aufsicht und Reaktion aufwirft.<\/p>\n<p><strong>Hat die F\u00fchrung von MCAST Konsequenzen zu tragen?<\/strong><br \/>\nBislang ist die F\u00fchrung von MCAST trotz der Untersuchung und der vorherigen Warnungen des Rechnungshofs weitgehend ohne \u00f6ffentliche Konsequenzen davongekommen.<\/p>\n<p><strong>K\u00f6nnen die Ergebnisse der Untersuchung w\u00e4hrend des Gerichtsverfahrens ver\u00f6ffentlicht werden?<\/strong><br \/>\nVerwaltungsuntersuchungen konzentrieren sich eher auf die Governance als auf die strafrechtliche Verantwortung, und ihre Ergebnisse k\u00f6nnen oft mit der entsprechenden rechtlichen Sorgfalt ver\u00f6ffentlicht werden.<\/p>\n<p><strong>Warum ist Transparenz in diesem Fall wichtig?<\/strong><br \/>\nTransparenz erm\u00f6glicht es der \u00d6ffentlichkeit, institutionelle Vers\u00e4umnisse zu verstehen, vorgeschlagene Reformen zu bewerten und das Vertrauen in die \u00f6ffentliche Verwaltung aufrechtzuerhalten.<\/p>\n<p><strong>Was sind die weiterreichenden Auswirkungen dieses Falls?<\/strong><br \/>\nDer Fall verdeutlicht die Herausforderungen bei der Gew\u00e4hrleistung von Rechenschaftspflicht, Transparenz und wirksamer Aufsicht \u00fcber \u00f6ffentlich finanzierte Institutionen in Malta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Entscheidung des Bildungsministeriums, die vollst\u00e4ndigen Ergebnisse einer Verwaltungsuntersuchung zu den Finanzkontrollen am Malta College of Arts Science and Technology nicht zu ver\u00f6ffentlichen, hat erneut langj\u00e4hrige Bedenken hinsichtlich der Transparenz, Rechenschaftspflicht und Governance innerhalb \u00f6ffentlicher Einrichtungen aufkommen lassen. Trotz wiederholter Anfragen von Journalisten und klarer Aussagen des Untersuchungsausschusses selbst, dass die detaillierten Ergebnisse ein integraler Bestandteil des Berichts sind, hat das Ministerium die Ver\u00f6ffentlichung auf eine kurze Pressemitteilung beschr\u00e4nkt.<\/p>\n","protected":false},"author":8,"featured_media":109123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[579],"tags":[57265,85026,53581,85023,84100,13513,788,41962,85025,85024,85022],"class_list":["post-109125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-malta-news","tag-bildungsministerium-malta","tag-bildungssektor-malta","tag-clifton-grima-de","tag-finanzkontrollen","tag-institutionelle-transparenz","tag-mcast-de","tag-news-malta-de","tag-oeffentliche-verwaltung","tag-oeffentlicher-sektor-aufsicht","tag-rechenschaftsstandards","tag-verwaltungspruefung"],"acf":[],"_links":{"self":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/109125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/comments?post=109125"}],"version-history":[{"count":0,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/109125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media\/109123"}],"wp:attachment":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media?parent=109125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/categories?post=109125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/tags?post=109125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}