{"id":77682,"date":"2025-04-12T12:11:29","date_gmt":"2025-04-12T10:11:29","guid":{"rendered":"https:\/\/malta-media.com\/?p=77682"},"modified":"2025-04-12T12:11:29","modified_gmt":"2025-04-12T10:11:29","slug":"petition-fordert-dass-manoel-island-ein-nationalpark-wird","status":"publish","type":"post","link":"https:\/\/malta-media.com\/de\/petition-fordert-dass-manoel-island-ein-nationalpark-wird\/","title":{"rendered":"Petition fordert, dass Manoel Island ein Nationalpark wird"},"content":{"rendered":"<p><strong>In den letzten Wochen haben mehr als 5.000 Menschen eine parlamentarische Petition unterzeichnet, in der die Regierung aufgefordert wird, die Insel Manoel wieder in \u00f6ffentliche Hand zu geben. Die Petition spricht sich daf\u00fcr aus, die Insel in einen Nationalpark umzuwandeln, um das einzigartige Natur- und Kulturerbe Maltas zu bewahren. Die Petition wurde am 26. M\u00e4rz ins Leben gerufen und hat in nur etwas mehr als zwei Wochen erhebliche Unterst\u00fctzung erhalten.<\/strong><\/p>\n<h2>Eine schnell wachsende Bewegung<\/h2>\n<p>Die Kampagne f\u00fcr den Erhalt der Insel Manoel hat schnell an Schwung gewonnen, und ihre Unterst\u00fctzer sind durch die starke \u00f6ffentliche Resonanz ermutigt. Marie Claire Gatt, eine Sprecherin der Kampagne, brachte den wachsenden Wunsch der \u00d6ffentlichkeit zum Ausdruck, dass die Insel ein f\u00fcr alle zug\u00e4nglicher Ort bleiben soll. \u201eDas Erreichen von 5.000 Unterschriften in etwas mehr als zwei Wochen ist ein starkes Zeichen f\u00fcr den Wunsch der \u00d6ffentlichkeit, dass die Insel Manoel ein Ort bleibt, der f\u00fcr alle zug\u00e4nglich ist\u201c, so Gatt.<\/p>\n<p>Die Petition wird von der Organisation \u201eManoel Island\u201c angef\u00fchrt: Post G\u0127alina (Ein Ort f\u00fcr uns)&#8221;, die von Moviment Graffitti und Flimkien g\u0127al Ambent A\u0127jar, zwei Organisationen, die sich f\u00fcr den Erhalt der Umwelt einsetzen, geleitet wird. Neben diesen Organisationen unterst\u00fctzen \u00fcber 40 weitere Gruppen die Initiative, darunter Organisationen, die sich mit Fitness und geistiger Gesundheit befassen. Auch die Umweltkommission der Kirche hat sich der Sache angeschlossen.<\/p>\n<h2>Wachsender Einfluss der Kampagne<\/h2>\n<p>Die Unterst\u00fctzung f\u00fcr die Petition beschr\u00e4nkt sich nicht nur auf Umweltsch\u00fctzer und Aktivisten. Robert Louis Fenech, ein weiterer Vertreter der Kampagne, \u00e4u\u00dferte sich optimistisch \u00fcber die breite Unterst\u00fctzung, die die Petition gefunden hat. &#8220;Die breite Unterst\u00fctzung, die wir sowohl von Organisationen als auch von der breiten \u00d6ffentlichkeit erfahren, ist sehr ermutigend. Sie zeigt, dass die Menschen die Hoffnung nicht aufgegeben haben, etwas bewirken zu k\u00f6nnen&#8221;, so Fenech. Dieses Gef\u00fchl spiegelt die \u00dcberzeugung wider, dass die \u00d6ffentlichkeit eine Rolle bei der Gestaltung der Zukunft ihrer gemeinsamen R\u00e4ume und ihres Naturerbes spielen muss.<\/p>\n<p>Bei der Petition f\u00fcr einen Nationalpark auf der Insel Manoel geht es nicht nur darum, das Land wegen seiner nat\u00fcrlichen Sch\u00f6nheit zu erhalten, sondern auch darum, ein kulturelles Wahrzeichen f\u00fcr k\u00fcnftige Generationen zu bewahren. Die Insel Manoel beherbergt mehrere historische Geb\u00e4ude, darunter das Lazzaretto-Geb\u00e4ude, das \u00e4lteste Pestkrankenhaus Europas. Die Erhaltung und Restaurierung dieser historischen Geb\u00e4ude k\u00f6nnte die Insel zu einem wertvollen Kulturgut machen, das den Menschen nicht nur eine gr\u00fcne Freifl\u00e4che bietet, sondern auch zum Verweilen einl\u00e4dt.<\/p>\n<h2>Die Rolle von MIDI und die Zukunft der Insel<\/h2>\n<p>Die Insel Manoel unterliegt derzeit einem langfristigen Pachtvertrag mit MIDI, einem privaten Firmenkonsortium, das die Insel f\u00fcr 99 Jahre gepachtet hat. Dieser Vertrag erlaubt es MIDI, Entwicklungsprojekte auf der Insel durchzuf\u00fchren, darunter Pl\u00e4ne f\u00fcr etwa 400 Luxuswohnungen und mehrere kommerzielle Einrichtungen, wie ein Hotel im Lazzaretto-Geb\u00e4ude. Die laufenden Verhandlungen zwischen MIDI und der Regierung \u00fcber die Verl\u00e4ngerung der urspr\u00fcnglichen Frist f\u00fcr das Projekt bis zum Jahr 2026 haben nach Angaben von Vertretern der Kampagne jedoch ein neues \u201eFenster der M\u00f6glichkeiten\u201c ge\u00f6ffnet.<\/p>\n<p>Fenech erkl\u00e4rte, dass die \u00d6ffentlichkeit eine seltene Gelegenheit hat, die Zukunft der Insel zu beeinflussen, da sowohl MIDI als auch die Regierung in Gespr\u00e4chen \u00fcber eine Verl\u00e4ngerung des Projektzeitplans stehen. &#8220;MIDI und die Regierung sitzen bereits an einem Tisch, um die Zukunft des Projekts zu diskutieren. Das gibt der \u00d6ffentlichkeit ein kleines Zeitfenster, um zu handeln &#8211; eine Gelegenheit, die wir seit 25 Jahren nicht mehr hatten und auch nie wieder haben werden&#8221;, betonte er. Die Kampagne arbeitet daran, diese seltene Chance zu nutzen und auf eine L\u00f6sung zu dr\u00e4ngen, die den B\u00fcrgern, der Umwelt und dem kulturellen Erbe der Insel zugute kommt.<\/p>\n<h2>Die Kampagne fordert eine &#8220;f\u00fcr beide Seiten vorteilhafte&#8221; L\u00f6sung<\/h2>\n<p>Die Aktivisten glauben, dass eine f\u00fcr beide Seiten vorteilhafte L\u00f6sung m\u00f6glich ist, die die Erhaltung des nat\u00fcrlichen und historischen Erbes der Insel erm\u00f6glicht und gleichzeitig eine gewisse Entwicklung zul\u00e4sst. In der Petition wird insbesondere die R\u00fcckgabe der Insel Manoel in \u00f6ffentliches Eigentum sowie die Umwandlung der Insel in einen \u00f6ffentlichen Park gefordert. Die geplante Wohnbebauung auf der Insel w\u00fcrde durch gr\u00fcne Freifl\u00e4chen und Erholungseinrichtungen ersetzt, wodurch eine \u201egr\u00fcne Lunge\u201c f\u00fcr das gesamte Gebiet geschaffen w\u00fcrde, hei\u00dft es in der Petition.<\/p>\n<p>Dar\u00fcber hinaus setzt sich die Kampagne f\u00fcr die Restaurierung und den Erhalt der historischen Geb\u00e4ude auf der Insel ein. Dazu geh\u00f6rt das Lazzaretto, das ikonische Pestkrankenhaus der Insel, das zu einem einzigartigen kulturellen Wahrzeichen werden k\u00f6nnte. Die Aktivisten argumentieren, dass die Insel Manoel nach ihrer Restaurierung einen Ort bieten k\u00f6nnte, an dem Bewohner und Besucher gleicherma\u00dfen die reiche Geschichte und Kultur Maltas erleben und gleichzeitig eine ruhige Gr\u00fcnfl\u00e4che genie\u00dfen k\u00f6nnten.<\/p>\n<h2>Das Potenzial der Insel Manoel als \u00f6ffentlicher Park<\/h2>\n<p>Die Koordinatorin von Flimkien g\u0127al Ambjent A\u0127jar (FAA), Astrid Vella, hat ebenfalls ihre Unterst\u00fctzung f\u00fcr die Ziele der Kampagne zum Ausdruck gebracht, insbesondere f\u00fcr die Restaurierung der historischen Geb\u00e4ude auf der Insel. Sie ist der Ansicht, dass die Insel mit der richtigen Pflege und Investition zu einer gr\u00fcnen Oase werden k\u00f6nnte, von der sowohl die lokale Bev\u00f6lkerung als auch die Touristen profitieren w\u00fcrden. \u201eSobald die Insel restauriert ist, hat sie ein enormes Potenzial als gr\u00fcner Freiraum, in dem Bewohner und Besucher gleicherma\u00dfen die einzigartige Geschichte Maltas genie\u00dfen k\u00f6nnen\u201c, so Vella.<\/p>\n<p>Der Vorschlag, die Manoel-Insel in einen nationalen Kulturerbe-Park zu verwandeln, ist Teil einer umfassenderen Vision f\u00fcr die Erhaltung \u00f6ffentlicher R\u00e4ume in Malta. Durch die Umwandlung der Manoel-Insel in einen \u00f6ffentlichen Park w\u00fcrde die Regierung nicht nur ein wichtiges St\u00fcck des maltesischen Kulturerbes bewahren, sondern auch ein wertvolles Erholungsgebiet f\u00fcr die lokale Bev\u00f6lkerung schaffen. Solche Fl\u00e4chen werden immer wichtiger, da die Stadtentwicklung weiter voranschreitet und die Nachfrage nach Gr\u00fcnfl\u00e4chen steigt.<\/p>\n<h2>N\u00e4chste Schritte f\u00fcr die Kampagne<\/h2>\n<p>Da die \u00f6ffentliche Unterst\u00fctzung weiter w\u00e4chst, konzentrieren sich die Aktivisten nun darauf, noch mehr Unterschriften f\u00fcr die Petition zu sammeln und das Bewusstsein f\u00fcr die Bedeutung des Erhalts der Insel Manoel zu sch\u00e4rfen. Sie rufen alle, die ihre Vision eines \u00f6ffentlichen Parks teilen, dazu auf, die Petition zu unterzeichnen und andere dazu zu ermutigen, das Gleiche zu tun. Die Website der Kampagne bietet weitere Informationen und l\u00e4dt dazu ein, sich der Bewegung anzuschlie\u00dfen.<\/p>\n<p>Die Petition fordert das maltesische Parlament auf, mit MIDI, dem derzeitigen P\u00e4chter der Insel, zu verhandeln, um die Insel wieder in \u00f6ffentliches Eigentum zu \u00fcberf\u00fchren. Neben der Schaffung eines Nationalparks wird in der Petition die Entwicklung von Gr\u00fcnfl\u00e4chen und Erholungsgebieten anstelle der geplanten Luxuswohnungen gefordert. Au\u00dferdem wird die Restaurierung und Erhaltung der historischen Geb\u00e4ude der Insel gefordert, damit auch k\u00fcnftige Generationen in den Genuss der nat\u00fcrlichen Sch\u00f6nheit und der historischen Bedeutung der Insel Manoel kommen k\u00f6nnen.<\/p>\n<h2>Schlussfolgerung<\/h2>\n<p><strong>Die Petition zur Umwandlung der Insel Manoel in einen Nationalpark ist eine bedeutende Bewegung, die den Wunsch der \u00d6ffentlichkeit unterstreicht, das kulturelle und nat\u00fcrliche Erbe Maltas zu erhalten. Mit der tatkr\u00e4ftigen Unterst\u00fctzung von \u00fcber 5.000 Unterzeichnern und zahlreichen Organisationen hat die Kampagne in kurzer Zeit betr\u00e4chtlich an Schwung gewonnen. W\u00e4hrend die Verhandlungen zwischen MIDI und der Regierung weitergehen, ist die Beteiligung der \u00d6ffentlichkeit an der Gestaltung der Zukunft der Insel wichtiger denn je. Indem sie sich f\u00fcr einen gr\u00fcnen, zug\u00e4nglichen Raum einsetzt, der sowohl die Umwelt als auch das Erbe der Insel respektiert, setzt sich die Kampagne f\u00fcr eine L\u00f6sung ein, die allen Maltesern zugute kommt.<\/strong><\/p>\n<h2>FAQs<\/h2>\n<p><strong>Was ist das Ziel der Petition f\u00fcr die Insel Manoel?<\/strong><br \/>\nZiel ist es, die Insel Manoel wieder in \u00f6ffentliches Eigentum zu \u00fcberf\u00fchren und sie in einen Nationalpark umzuwandeln, der dem nat\u00fcrlichen und kulturellen Erbe Maltas gewidmet ist.<\/p>\n<p><strong>Wie viele Menschen haben die Petition unterzeichnet?<\/strong><br \/>\nMehr als 5.000 Menschen haben die Petition in etwas mehr als zwei Wochen unterzeichnet, was eine starke \u00f6ffentliche Unterst\u00fctzung f\u00fcr das Anliegen zeigt.<\/p>\n<p><strong>Wer f\u00fchrt die Kampagne an?<\/strong><br \/>\nDie Kampagne wird von Moviment Graffitti und Flimkien g\u0127al Ambent A\u0127jar geleitet, zwei Organisationen, die sich f\u00fcr die Erhaltung von Umwelt und Kultur einsetzen.<\/p>\n<p><strong>Was ist der Plan von MIDI f\u00fcr die Insel Manoel?<\/strong><br \/>\nMIDI plant die Entwicklung der Insel Manoel mit rund 400 Luxuswohnungen und kommerziellen Einrichtungen, darunter ein Hotel im historischen Lazzaretto-Geb\u00e4ude.<\/p>\n<p><strong>Was ist das Lazzaretto-Geb\u00e4ude?<\/strong><br \/>\nDas Lazzaretto-Geb\u00e4ude ist das \u00e4lteste Pestkrankenhaus Europas und ein wichtiges historisches Wahrzeichen der Insel Manoel.<\/p>\n<p><strong>Wie kann ich die Petition unterst\u00fctzen?<\/strong><br \/>\nSie k\u00f6nnen die Petition unterst\u00fctzen, indem Sie sie auf der Website der Kampagne unterzeichnen und sie an andere weiterleiten, die sich f\u00fcr den Erhalt der Insel Manoel interessieren k\u00f6nnten.<\/p>\n<p><strong>Was ist die Vision f\u00fcr die Insel Manoel?<\/strong><br \/>\nDie Vision ist die Umwandlung der Insel Manoel in einen \u00f6ffentlichen Park mit Gr\u00fcnfl\u00e4chen, Erholungseinrichtungen und restaurierten historischen Geb\u00e4uden.<\/p>\n<p><strong>Warum ist die Petition wichtig?<\/strong><br \/>\nDie Petition ist wichtig, weil sie der \u00d6ffentlichkeit eine seltene Gelegenheit bietet, w\u00e4hrend der laufenden Verhandlungen zwischen der Regierung und MIDI Einfluss auf die Zukunft der Insel Manoel zu nehmen.<\/p>\n<p><strong>Was ist die vorgeschlagene Alternative zu den Luxuswohnungen?<\/strong><br \/>\nIn der Petition wird gefordert, die Luxuswohnungen durch gr\u00fcne Freifl\u00e4chen und Erholungsgebiete zu ersetzen und so eine \u201egr\u00fcne Lunge\u201c f\u00fcr das Gebiet zu schaffen.<\/p>\n<p><strong>Welches Potenzial hat die Insel Manoel als Nationalpark?<\/strong><br \/>\nNach ihrer Wiederherstellung k\u00f6nnte die Insel Manoel zu einer gr\u00fcnen Oase f\u00fcr Bewohner und Besucher werden, die sowohl kulturelle als auch nat\u00fcrliche Erfahrungen bietet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Wochen haben mehr als 5.000 Menschen eine parlamentarische Petition unterzeichnet, in der die Regierung aufgefordert wird, die Insel Manoel wieder in \u00f6ffentliche Hand zu geben. Die Petition spricht sich daf\u00fcr aus, die Insel in einen Nationalpark umzuwandeln, um das einzigartige Natur- und Kulturerbe Maltas zu bewahren. Die Petition wurde am 26. M\u00e4rz ins Leben gerufen und hat in nur etwas mehr als zwei Wochen erhebliche Unterst\u00fctzung erhalten.<\/p>\n","protected":false},"author":12,"featured_media":77680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[579],"tags":[55167,40910,55165,587,37685,11109,11111,55163,788,55164,55166,4593],"class_list":["post-77682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-malta-news","tag-flimkien-ghal-ambent-ahjar-de","tag-gruene-raeume","tag-luxuswohnungen","tag-malta-news","tag-malta-erbe","tag-manoel-island-de","tag-moviment-graffitti-de","tag-nationalpark","tag-news-malta-de","tag-oeffentliche-eigentuemerschaft","tag-petition-de","tag-umweltschutz"],"acf":[],"_links":{"self":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/77682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/comments?post=77682"}],"version-history":[{"count":0,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/77682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media\/77680"}],"wp:attachment":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media?parent=77682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/categories?post=77682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/tags?post=77682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}