{"id":88075,"date":"2025-07-09T14:33:12","date_gmt":"2025-07-09T12:33:12","guid":{"rendered":"https:\/\/malta-media.com\/?p=88075"},"modified":"2025-07-09T14:33:12","modified_gmt":"2025-07-09T12:33:12","slug":"ksa-bestraft-influencer-leftlanepapi-wegen-illegaler-werbung","status":"publish","type":"post","link":"https:\/\/malta-media.com\/de\/ksa-bestraft-influencer-leftlanepapi-wegen-illegaler-werbung\/","title":{"rendered":"KSA bestraft Influencer LeftlanePapi wegen illegaler Werbung"},"content":{"rendered":"<p><strong>Die niederl\u00e4ndische Gl\u00fccksspielbeh\u00f6rde Kansspelautoriteit (KSA) hat entschiedene Ma\u00dfnahmen zur Bek\u00e4mpfung der Werbung f\u00fcr nicht genehmigtes Gl\u00fccksspiel in den Niederlanden ergriffen und eine bedingte Strafverf\u00fcgung gegen den YouTube-Influencer LeftlanePapi erlassen. Die Ma\u00dfnahme folgt auf die fortgesetzte Ver\u00f6ffentlichung von Videos auf seinem Kanal, in denen nicht lizenzierte Online-Gl\u00fccksspielanbieter beworben und vorgestellt werden.<\/strong><\/p>\n<p>Laut KSA war der Influencer wiederholt an der \u00dcbertragung von <a href=\"https:\/\/malta-media.com\/ALEA\" title=\"ALEA\" class=\"pretty-link-keyword\"rel=\"\" target=\"_blank\">Live<\/a>-Streams illegaler Gl\u00fccksspielsitzungen beteiligt, begleitet von expliziten Werbeinhalten, die die Zuschauer dazu ermutigten, auf Plattformen zuzugreifen und an Gl\u00fccksspielen teilzunehmen, die nicht \u00fcber die nach niederl\u00e4ndischem Recht erforderlichen Lizenzen verf\u00fcgen.<\/p>\n<p>Die Beh\u00f6rde sprach zun\u00e4chst eine formelle Verwarnung aus und bot dem Influencer die M\u00f6glichkeit, die nicht konformen Inhalte freiwillig zu entfernen und die weitere Werbung einzustellen. Als LeftlanePapi jedoch nicht entsprechend handelte und weiterhin \u00e4hnliche Inhalte ver\u00f6ffentlichte, versch\u00e4rfte die KSA die Durchsetzung, indem sie eine bedingte Geldstrafe verh\u00e4ngte, um durch rechtlichen und finanziellen Druck die Einhaltung der Vorschriften zu erzwingen.<\/p>\n<h2>Details zur verh\u00e4ngten Strafe<\/h2>\n<p>Die KSA hat die Struktur der in diesem Fall verh\u00e4ngten Sanktion pr\u00e4zisiert. Die Strafe betr\u00e4gt 25.000 \u20ac pro Versto\u00df, mit einer maximalen Gesamtgrenze von 75.000 \u20ac. Diese Struktur ist Teil der abgestuften Durchsetzungsstrategie der Regulierungsbeh\u00f6rde, die darauf abzielt, Verst\u00f6\u00dfe schrittweise zu ahnden, ohne sofort auf Strafverfahren oder administrative Sanktionen wie Strafverfolgung zur\u00fcckzugreifen.<\/p>\n<p>Der Influencer muss nun alle bestehenden Werbeinhalte im Zusammenhang mit illegalen Gl\u00fccksspielplattformen entfernen und darf keine neuen Inhalte ver\u00f6ffentlichen, die f\u00fcr nicht lizenzierte Gl\u00fccksspielanbieter werben oder auf diese verweisen. Weitere Verst\u00f6\u00dfe f\u00fchren zu den genannten Geldstrafen.<\/p>\n<h2>Die neue zweigleisige Durchsetzungsstrategie der KSA<\/h2>\n<p>Dieser Fall ist eine klare Anwendung der k\u00fcrzlich von der KSA verabschiedeten zweigleisigen Durchsetzungspolitik f\u00fcr Social-Media-Influencer und Content-Ersteller. Diese Politik spiegelt einen strategischen Wandel der Beh\u00f6rde wider, der eine agilere und direktere Reaktion auf Online-Verst\u00f6\u00dfe erm\u00f6glicht, die sich schnell \u00fcber soziale Plattformen verbreiten und teilen lassen.<\/p>\n<p>Nach diesem Modell gilt Folgendes:<\/p>\n<ul>\n<li>Wenn ein Versto\u00df festgestellt wird, erh\u00e4lt der Influencer eine offizielle Mitteilung und hat 48 Stunden Zeit, um alle beanstandeten Inhalte zu entfernen.<\/li>\n<li>Wird diese Frist nicht eingehalten, eskaliert die KSA die Angelegenheit, indem sie die betreffende Social-Media-Plattform benachrichtigt und die Entfernung der Inhalte direkt auf Plattformebene verlangt.<\/li>\n<li>Gleichzeitig kann die KSA gem\u00e4\u00df dem Verwaltungsrecht Geldstrafen verh\u00e4ngen, wie dies im Fall von LeftlanePapi geschehen ist.<\/li>\n<\/ul>\n<p>Diese Methode zielt laut KSA darauf ab, den Schaden f\u00fcr Verbraucher, insbesondere f\u00fcr Minderj\u00e4hrige und schutzbed\u00fcrftige Personen, zu minimieren, indem sichergestellt wird, dass rechtswidrige Inhalte auch ohne die Zusammenarbeit des Urhebers der Inhalte schnell entfernt werden.<\/p>\n<h2>Der rechtliche Rahmen f\u00fcr Gl\u00fccksspielwerbung in den Niederlanden<\/h2>\n<p>Die Niederlande unterhalten einen streng regulierten Gl\u00fccksspielmarkt. Nach dem Gesetz \u00fcber Ferngl\u00fccksspiele (Wet Kansspelen op afstand) d\u00fcrfen nur Betreiber, die \u00fcber eine Lizenz der KSA verf\u00fcgen, niederl\u00e4ndischen Verbrauchern legal Online-Gl\u00fccksspiele anbieten. Das gleiche Gesetz sieht strenge Beschr\u00e4nkungen f\u00fcr Werbe- und Verkaufsf\u00f6rderungsma\u00dfnahmen vor, insbesondere wenn solche Inhalte schutzbed\u00fcrftige Personen erreichen oder Verbraucher irref\u00fchren k\u00f6nnten.<\/p>\n<p>Influencern und Affiliates ist es gesetzlich untersagt, f\u00fcr nicht lizenzierte Gl\u00fccksspielanbieter zu werben oder <a href=\"https:\/\/malta-media.com\/ads\" title=\"Advertise PDF\" class=\"pretty-link-keyword\"rel=\"\" target=\"_blank\">Traffic<\/a> auf deren Websites zu lenken. Jede solche Handlung wird sowohl nach dem Gl\u00fccksspielgesetz als auch nach dem niederl\u00e4ndischen Verbraucherschutzgesetz als illegale Gesch\u00e4ftspraxis eingestuft.<\/p>\n<p>Das Gesetz erm\u00e4chtigt die KSA dar\u00fcber hinaus, administrative Sanktionen, Geldstrafen oder bedingte Strafen zu verh\u00e4ngen, um die Einhaltung der Vorschriften durchzusetzen. In einigen F\u00e4llen kann bei schweren oder wiederholten Verst\u00f6\u00dfen auch eine strafrechtliche Verfolgung in Zusammenarbeit mit der niederl\u00e4ndischen Staatsanwaltschaft erfolgen.<\/p>\n<h2>Die Rolle der sozialen Medien bei der Werbung f\u00fcr Gl\u00fccksspiele<\/h2>\n<p>Die KSA hat zunehmend Bedenken hinsichtlich des wachsenden Einflusses der sozialen Medien bei der Werbung f\u00fcr nicht lizenzierte Gl\u00fccksspiele ge\u00e4u\u00dfert, insbesondere durch Influencer, die oft ein gro\u00dfes Publikum haben, darunter auch Minderj\u00e4hrige.<\/p>\n<p>Die Regulierungsbeh\u00f6rde betont, dass selbst die passive Konfrontation mit Gl\u00fccksspielinhalten \u2013 wie das Anschauen eines Streams ohne aktive Beteiligung \u2013 eine Form der indirekten Werbung darstellen kann, insbesondere wenn sie mit Links, Markenerw\u00e4hnungen oder ausdr\u00fccklichen Empfehlungen illegaler Betreiber einhergeht.<\/p>\n<p>Dieser Fall veranschaulicht, wie Influencer als informelle Partner fungieren und m\u00f6glicherweise Verg\u00fctungen oder Vorteile erhalten, wenn sie Nutzer auf Gl\u00fccksspiel-Websites leiten. Die KSA hat erkl\u00e4rt, dass sie solche Praktiken nicht tolerieren wird, insbesondere wenn sie gegen die durch niederl\u00e4ndisches Recht festgelegten Schutzbestimmungen versto\u00dfen.<\/p>\n<h2>Weiterreichende Auswirkungen f\u00fcr Influencer und Content-Ersteller<\/h2>\n<p>Die Durchsetzungsma\u00dfnahme gegen LeftlanePapi ist kein Einzelfall. Die KSA hat \u00f6ffentlich best\u00e4tigt, dass sie mehrere andere Influencer, die auf YouTube, TikTok, Instagram und \u00e4hnlichen Plattformen t\u00e4tig sind, verwarnt hat. Diese Personen wurden nun offiziell darauf hingewiesen, dass weitere Verst\u00f6\u00dfe zu \u00e4hnlichen oder strengeren Strafen f\u00fchren k\u00f6nnen.<\/p>\n<p>Dar\u00fcber hinaus beabsichtigt die KSA, ihre Durchsetzungsstrategie durch die Zusammenarbeit mit internationalen Regulierungsbeh\u00f6rden und digitalen Plattformen zu erweitern, um grenz\u00fcberschreitende Verst\u00f6\u00dfe zu bek\u00e4mpfen. Da viele nicht lizenzierte Gl\u00fccksspiel-Websites von Offshore-Gerichtsbarkeiten aus betrieben werden, reicht die lokale Durchsetzung allein nicht aus. Durch die Zusammenarbeit auf Plattformebene und die Nutzung internationaler Rahmenwerke f\u00fcr die digitale Governance hofft die KSA, die Reichweite und Auswirkungen solcher rechtswidrigen Inhalte zu verringern.<\/p>\n<h2>Ethische und verbraucherschutzrechtliche Bedenken<\/h2>\n<p>Eines der zentralen Anliegen, das die Ma\u00dfnahmen der KSA motiviert, ist der Schutz der Verbraucher, insbesondere junger Menschen. Studien haben gezeigt, dass Gl\u00fccksspielinhalte in sozialen Medien riskante Verhaltensweisen normalisieren, die wahrgenommene Risiken verringern und die Wahrscheinlichkeit einer zuk\u00fcnftigen Teilnahme am Gl\u00fccksspiel erh\u00f6hen k\u00f6nnen.<\/p>\n<p>Die niederl\u00e4ndische Gl\u00fccksspielgesetzgebung basiert auf dem Prinzip des verantwortungsvollen Gl\u00fccksspiels (verantwoord spelen) und verpflichtet lizenzierte Betreiber und ihre Marketingpartner, aktiv Ma\u00dfnahmen zur Verringerung des Risikos einer Gl\u00fccksspielsucht und zum Schutz von Personen vor finanziellen Sch\u00e4den umzusetzen. Die Werbung f\u00fcr illegale Anbieter untergr\u00e4bt diese Bem\u00fchungen, da solche Plattformen in der Regel nicht an Verbraucherschutzstandards, Einzahlungslimits oder Transparenzanforderungen gebunden sind.<\/p>\n<p>Indem Influencer Nutzer an nicht lizenzierte Betreiber weiterleiten d\u00fcrfen, wird die \u00d6ffentlichkeit Dienstleistungen ausgesetzt, denen m\u00f6glicherweise Schutzma\u00dfnahmen wie Identit\u00e4tspr\u00fcfungen, Garantien f\u00fcr faires Spielen und Streitbeilegungsmechanismen fehlen.<\/p>\n<h2>Die sich wandelnde Rolle der Strafverfolgung im digitalen Zeitalter<\/h2>\n<p>Dieser Fall markiert auch eine Entwicklung in der Art und Weise, wie Regulierungsbeh\u00f6rden auf digitale Verst\u00f6\u00dfe reagieren. Traditionelle Strafverfolgungsans\u00e4tze \u2013 wie Gerichtsbeschl\u00fcsse oder Geldstrafen \u2013 sind m\u00f6glicherweise nicht gut geeignet, um virale Inhalte in sozialen Medien zu bek\u00e4mpfen. Stattdessen stellen bedingte Strafen in Kombination mit schnellen Antr\u00e4gen auf Plattform-L\u00f6schung ein neues Hybridmodell dar, das auf das digitale Zeitalter zugeschnitten ist.<\/p>\n<p>In Zukunft k\u00f6nnte die KSA algorithmische \u00dcberwachungsinstrumente und die Zusammenarbeit mit KI-Inhaltsscannern pr\u00fcfen, um Verst\u00f6\u00dfe proaktiv zu identifizieren. \u00c4hnliche Bem\u00fchungen wurden auch in anderen L\u00e4ndern wie Gro\u00dfbritannien und Deutschland unternommen, wo Gl\u00fccksspielaufsichtsbeh\u00f6rden automatisierte Systeme einsetzen, um illegale Werbung und Influencer-Empfehlungen aufzudecken.<\/p>\n<h2>Keine Toleranz f\u00fcr Verst\u00f6\u00dfe<\/h2>\n<p>Die KSA hat in dieser Angelegenheit einen entschlossenen Ton angeschlagen. Sie hat deutlich gemacht, dass anhaltende Verst\u00f6\u00dfe nicht toleriert werden und dass diejenigen, die versuchen, das niederl\u00e4ndische Gl\u00fccksspielgesetz zu umgehen \u2013 sei es durch Affiliates, verdeckte Sponsoring-Aktivit\u00e4ten oder nicht zur\u00fcckverfolgbare Plattformen \u2013 mit regulatorischen Konsequenzen rechnen m\u00fcssen.<\/p>\n<p>In einer Erkl\u00e4rung, die der Vollstreckungsentscheidung beigef\u00fcgt war, bekr\u00e4ftigte die KSA:<\/p>\n<p>\u201eDie Werbung f\u00fcr illegales Gl\u00fccksspiel, auch \u00fcber soziale Medien, stellt ein ernstes Risiko f\u00fcr die \u00f6ffentliche Ordnung und die Verbrauchersicherheit dar. Wir werden weiterhin entschlossen gegen diejenigen vorgehen, die den Rechtsrahmen untergraben.\u201c<\/p>\n<p>W\u00e4hrend die Identit\u00e4t des betroffenen Influencers aufgrund der Bekanntheit des Falls \u00f6ffentlich ist, hat sich die KSA geweigert, sich dazu zu \u00e4u\u00dfern, ob weitere zivil- oder strafrechtliche Verfahren folgen k\u00f6nnten, falls die Strafe keine abschreckende Wirkung auf k\u00fcnftige Verst\u00f6\u00dfe hat.<\/p>\n<h2>Fazit<\/h2>\n<p><strong>Der Fall LeftlanePapi markiert einen Wendepunkt in den laufenden Bem\u00fchungen der Niederlande, ihre strengen Gl\u00fccksspielgesetze im digitalen Bereich durchzusetzen. Da soziale Medien weiterhin ein wirkungsvolles Instrument f\u00fcr Marketing und die Verbreitung von Inhalten sind, passen Regulierungsbeh\u00f6rden wie die KSA ihre Strategien an, um sicherzustellen, dass rechtswidriges Verhalten schnell und effektiv geahndet wird. Die gegen den Influencer verh\u00e4ngte bedingte Strafe unterstreicht die Null-Toleranz-Politik der KSA gegen\u00fcber der Werbung f\u00fcr illegales Gl\u00fccksspiel, insbesondere wenn gef\u00e4hrdete Zielgruppen wie Minderj\u00e4hrige gef\u00e4hrdet sind.<\/strong><\/p>\n<p><strong>Diese Ma\u00dfnahme sendet eine klare Botschaft an Influencer, Affiliate-Vermarkter und Content-Ersteller: Die Einhaltung der Gl\u00fccksspielgesetze ist keine Option, und Verst\u00f6\u00dfe haben finanzielle und rechtliche Konsequenzen. Durch ihre zweigleisige Durchsetzungsstrategie \u2013 eine Kombination aus direkten Verwarnungen, Strafen und Zusammenarbeit mit digitalen Plattformen \u2013 zeigt die KSA, dass sie sowohl \u00fcber die Befugnisse als auch \u00fcber die Instrumente verf\u00fcgt, um die \u00f6ffentliche Sicherheit und die regulatorischen Standards in einer sich st\u00e4ndig weiterentwickelnden Online-Landschaft aufrechtzuerhalten.<\/strong><\/p>\n<p><strong>Da die regulatorischen Rahmenbedingungen in Europa und dar\u00fcber hinaus immer strenger werden, k\u00f6nnte dieser Fall als Pr\u00e4zedenzfall dienen, nicht nur f\u00fcr die Art und Weise, wie solche Verst\u00f6\u00dfe in den Niederlanden geahndet werden, sondern auch f\u00fcr die Zusammenarbeit internationaler Regulierungsbeh\u00f6rden zum Schutz digitaler R\u00e4ume vor illegaler Gl\u00fccksspielwerbung. Influencer, die sich an solchen Praktiken beteiligen oder diese erm\u00f6glichen, sollten ihre Inhalte, Verbindungen und Verantwortlichkeiten sorgf\u00e4ltig \u00fcberpr\u00fcfen, da der Spielraum f\u00fcr Fehler in diesem rechtlichen Umfeld immer kleiner wird.<\/strong><\/p>\n<h2>H\u00e4ufig gestellte Fragen<\/h2>\n<p><strong>Was hat LeftlanePapi getan, um eine Strafe von der KSA zu erhalten?<\/strong><br \/>\nLeftlanePapi hat \u00fcber seinen YouTube-Kanal f\u00fcr illegale Online-Gl\u00fccksspielanbieter geworben, indem er Livestreams geteilt und die Zuschauer dazu ermutigt hat, auf nicht lizenzierten Websites zu spielen.<\/p>\n<p><strong>Wie sah die Strafe der KSA aus?<\/strong><br \/>\nDie KSA verh\u00e4ngte eine bedingte Strafe in H\u00f6he von 25.000 \u20ac pro Versto\u00df, maximal 75.000 \u20ac, weil die illegalen Werbeinhalte nach einer formellen Verwarnung nicht entfernt wurden.<\/p>\n<p><strong>Ist die Werbung f\u00fcr nicht lizenzierte Gl\u00fccksspielinhalte in den Niederlanden illegal?<\/strong><br \/>\nJa, das niederl\u00e4ndische Recht verbietet die Werbung f\u00fcr Gl\u00fccksspielanbieter, die nicht von der KSA lizenziert sind. Influencer und Affiliates sind gesetzlich an diese Vorschrift gebunden.<\/p>\n<p><strong>Hat die KSA vor Verh\u00e4ngung der Geldstrafe eine Verwarnung ausgesprochen?<\/strong><br \/>\nJa, LeftlanePapi wurde vorab benachrichtigt und hatte 48 Stunden Zeit, um die beanstandeten Inhalte zu entfernen. Die Strafe wurde erst verh\u00e4ngt, nachdem diese Frist ignoriert wurde.<\/p>\n<p><strong>Kann YouTube f\u00fcr die Inhalte verantwortlich gemacht werden?<\/strong><br \/>\nDie KSA richtet sich in erster Linie an die Ersteller von Inhalten, informiert aber auch Plattformen wie YouTube, um die Entfernung sch\u00e4dlicher oder illegaler Inhalte sicherzustellen.<\/p>\n<p><strong>Werden auch andere Influencer von der KSA ins Visier genommen?<\/strong><br \/>\nJa, die KSA hat best\u00e4tigt, dass mehrere Influencer Verwarnungen erhalten haben, und sie wird weiterhin illegale Gl\u00fccksspielwerbung \u00fcberwachen.<\/p>\n<p><strong>Warum konzentriert sich die KSA auf soziale Medien?<\/strong><br \/>\nSocial-Media-Influencer k\u00f6nnen schnell ein gro\u00dfes Publikum erreichen, darunter auch Minderj\u00e4hrige, was sie zu einem risikoreichen Medium f\u00fcr unregulierte Gl\u00fccksspielwerbung macht.<\/p>\n<p><strong>Was ist eine bedingte Strafverf\u00fcgung?<\/strong><br \/>\nEs handelt sich um einen rechtlichen Mechanismus, der nur dann Geldstrafen verh\u00e4ngt, wenn die Person offiziellen Anordnungen, wie z. B. der Entfernung illegaler Inhalte, nicht nachkommt.<\/p>\n<p><strong>Arbeitet die KSA mit anderen L\u00e4ndern zusammen?<\/strong><br \/>\nJa, die KSA arbeitet mit internationalen Regulierungsbeh\u00f6rden zusammen, um grenz\u00fcberschreitende Verst\u00f6\u00dfe im Zusammenhang mit nicht lizenzierten Gl\u00fccksspieldiensten zu ahnden.<\/p>\n<p><strong>Was sollten Influencer \u00fcber die niederl\u00e4ndischen Gl\u00fccksspielgesetze wissen?<\/strong><br \/>\nInfluencer m\u00fcssen sicherstellen, dass sie keine nicht lizenzierten Gl\u00fccksspiele bewerben, da dies zu Geldstrafen, rechtlichen Schritten oder Rufsch\u00e4digung f\u00fchren kann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die niederl\u00e4ndische Gl\u00fccksspielbeh\u00f6rde Kansspelautoriteit (KSA) hat entschiedene Ma\u00dfnahmen zur Bek\u00e4mpfung der Werbung f\u00fcr nicht genehmigtes Gl\u00fccksspiel in den Niederlanden ergriffen und eine bedingte Strafverf\u00fcgung gegen den YouTube-Influencer LeftlanePapi erlassen. Die Ma\u00dfnahme folgt auf die fortgesetzte Ver\u00f6ffentlichung von Videos auf seinem Kanal, in denen nicht lizenzierte Online-Gl\u00fccksspielanbieter beworben und vorgestellt werden.<\/p>\n","protected":false},"author":12,"featured_media":88073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[868,577],"tags":[66963,880,597,804,66195,10238,815,66962,5238,61879,14880,9189,66961,1656,66960],"class_list":["post-88075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesetze","category-igaming-news-de","tag-affiliate-marketing-compliance-de","tag-gesetze","tag-igaming-de","tag-igaming-de-2","tag-illegale-gluecksspielwerbung","tag-ksa-de","tag-laws-de","tag-leftlanepapi-de","tag-niederlaendische-gluecksspielbehoerde","tag-niederlaendisches-gluecksspielrecht","tag-online-gluecksspielregulierung","tag-responsible-gambling-de","tag-social-media-ueberwachung","tag-verantwortungsbewusstes-spielen","tag-youtube-influencer-strafe"],"acf":[],"_links":{"self":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/88075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/comments?post=88075"}],"version-history":[{"count":0,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/posts\/88075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media\/88073"}],"wp:attachment":[{"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/media?parent=88075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/categories?post=88075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malta-media.com\/de\/wp-json\/wp\/v2\/tags?post=88075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}